{"id":6215,"date":"2023-02-15T10:30:00","date_gmt":"2023-02-15T09:30:00","guid":{"rendered":"https:\/\/anb030.de\/a\/?p=6215"},"modified":"2024-11-17T17:39:32","modified_gmt":"2024-11-17T16:39:32","slug":"next-bdays-scriptable","status":"publish","type":"post","link":"https:\/\/anb030.de\/a\/next-bdays-scriptable\/","title":{"rendered":"Next Bdays: Ein Scriptable-Widget zum anzeigen der demn\u00e4chst anstehenden vier Geburtstage"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"705\" src=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3395-1024x705.jpg\" alt=\"Titelbild: Anstehende Geburtstage per Scriptable-Widget \" class=\"wp-image-6219\" srcset=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3395-1024x705.jpg 1024w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3395-300x206.jpg 300w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3395-768x528.jpg 768w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3395-1536x1057.jpg 1536w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3395-2048x1409.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Manchmal ist mein K\u00f6rper auch nur Transportmittel meiner Gedanken und so hab ich mal wieder einen wichtigen Geburtstag verpasst. Nat\u00fcrlich bietet Apple seine Kalender Werksapplikation sowie Drittanbieter-Apps wie beispielsweise Fantastical diese Erinnerungsfunktion an, aber auch diese habe ich \u00fcbersehen. Das Problem ist hier, dass diese Erinnerungen per Push Mitteilungen auf dem Sperrbildschirm tags\u00fcber angezeigt werden und wenn man mehrere Mitteilungen auf seinen Sperrbildschirm hat, dann \u00fcbersieht man auch diese mal schnell. Und hier kommt ein JavaScript-Code f\u00fcr die Scriptable-App ins Spiel. Diese App erm\u00f6glicht es jedem iPhone- und iPad-Benutzer, seinen eigenen Sperrbildschirm oder &#8211; wie in diesem Fall &#8211; seinen eigenen Home-Bildschirm individuell zu gestalten. Einige <strong><a href=\"https:\/\/anb030.de\/a\/tag\/scriptable\/\">Beispiele<\/a><\/strong> f\u00fcr die Scriptable-App sind hier auf anb030.de schon vertreten! Wer ein gut gepflegtes iPhone Telefonbuch mit Geburtstagsdaten sein eigen nennt, der darf dann nat\u00fcrlich gerne weiterlesen. <\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Aber warum nun ein Widget mit der Scriptable-App? Ganz einfach, weil keine Kalender-App ein &#8211; nur &#8211; Geburtstags-Widget anbietet und weil eine zus\u00e4tzliche App aus dem AppStore heutzutage oft mit einer InAPP-Seuche zugepflastert ist oder weil es einfach &#8211; wieder &#8211; eine zus\u00e4tzliche App mehr auf dem Home-Bildschirm ist. Wie auch immer, meine Intention f\u00fcr das \u201eNext Bdays\u201c Widget war, dass es eine einfache L\u00f6sung sein sollte und da ist die Scriptable-App perfekt f\u00fcr geeignet. Eine App mit hunderten von M\u00f6glichkeiten und wenig Platzbedarf. Bei Interesse kann der Nutzer des JavaScript-Codes selbst Hand anlegen, um sich das Widget nach seinen W\u00fcnschen anzupassen. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3394-1024x1024.jpg\" alt=\"\" class=\"wp-image-6214\" srcset=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3394.jpg 1024w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3394-150x150.jpg 150w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3394-300x300.jpg 300w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3394-768x768.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\"><strong>Der besondere Widget-Stil in zwei Farbvarianten und mit iCloud-Drive Synchronisierung!<\/strong><\/h2>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">In Anlehnung an den Berliner Nahverkehr habe ich das Widget in zwei Farbvarianten erstellt. Zum einen f\u00fcr den eher dunklen Bildschirm im Stil der BVG mit den Farben Verkehrsgelb und Schwarz und zum anderen f\u00fcr den eher hellen Bildschirm im Stil der S-Bahn Berlin mit den Farben Ockergelb und Rubinrot. Es sollte also f\u00fcr jeden Geschmack etwas dabei sein. <\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Wenn man ein gut gepflegtes iPhone oder iPad Telefonbuch besitzt &#8211; gef\u00fcllt mit Geburtstagen &#8211; sollte das Widget einwandfrei funktionieren. Damit dies reibungslos klappt, legt der JavaScript-Code nach der ersten Ausf\u00fchrung in der Scriptable-App eine Kopie der Daten in eurem iCloud-Drive-Ordner ab. Das Schlagwort \u201eiCloud\u201c, das in diesem Zusammenhang genannt wurde, wird etwas sp\u00e4ter bei der Konfiguration wieder interessant.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\"><strong>Welche Voraussetzungen werden ben\u00f6tigt f\u00fcr das \u201eNext Bdays\u201c Widget?<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ungef\u00e4hr 5 Minuten Zeit <\/li>\n\n\n\n<li>Ein iPhone oder iPad mit iOS 16 oder neuer<\/li>\n\n\n\n<li>Ein gut gepflegtes Telefonbuch mit Geburtstags-Daten<\/li>\n\n\n\n<li>Die aktuelle <a rel=\"noreferrer noopener\" href=\"https:\/\/apps.apple.com\/de\/app\/scriptable\/id1405459188\" target=\"_blank\">Scriptable<\/a> App<\/li>\n\n\n\n<li>Der JavaScript-Code im <a href=\"https:\/\/anb030.de\/dl\/js_next_bdays_black.txt\">BVG Berlin<\/a> Stil<\/li>\n\n\n\n<li>Der JavaScript-Code im <a href=\"https:\/\/anb030.de\/dl\/js_next_bdays_yellow.txt\">S-Bahn Berlin<\/a> Stil <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\"><strong>Scriptable-App Downloaden und JavaScript-Code einf\u00fcgen!<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1. Kopiert euch einen der zwei JavaScript-Codes von oben oder von unten aus dem Kasten. Ist die Scriptable-App installiert, so muss diese ge\u00f6ffnet werden und dann oben rechts auf das kleine <strong>blaue<\/strong> \u201e<strong>+<\/strong>\u201c geklickt werden. <\/li>\n\n\n\n<li>2. <strong>Klickt einmal kurz <\/strong>in das leere \u201e<strong>Feld<\/strong>\u201c um den Tastatur-Modus zu \u00f6ffnen und ein weiteres Mal neben der \u201e<strong>1 I<\/strong>\u201c mit einem <strong>langen Fingerdruck<\/strong> um das Kontextmen\u00fcs mit der Option \u201e<strong>Einf\u00fcgen<\/strong>\u201c zu erhalten. Jetzt k\u00f6nnt Ihr hier den JavaScript-Code einf\u00fcgen!<\/li>\n\n\n\n<li>3. + 4. Bei diesen zwei Punkten k\u00f6nnt Ihr den eben erstellten Code noch mit einem \u201e<strong>Namen<\/strong>\u201c sowie \u201e<strong>Icon<\/strong>\u201c Versehen. <\/li>\n\n\n\n<li>5. Um jetzt alles abzuspeichern, gen\u00fcgt ein Klick oben links auf \u201e<strong>Done<\/strong>\u201c!<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3422-1024x640.jpg\" alt=\"Scriptable-App Downloaden und Code einf\u00fchren!\" class=\"wp-image-6238\" srcset=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3422-1024x640.jpg 1024w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3422-300x188.jpg 300w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3422-768x480.jpg 768w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3422.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\"><strong>Die Berechtigungen einholen f\u00fcr die Scriptable-App!<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1. Um den Zugriff auf die \u201e<strong>Kontakte<\/strong>\u201c vom iPhone\/iPad Telefonbuch zu berechtigen, muss zwingend beim ersten ausf\u00fchren des zuvor erstellten JavaScript-Code <strong>ein Klick<\/strong> auf das \u201e<strong>Next Bdays<\/strong>\u201c <strong>Banner erfolgen<\/strong>. <\/li>\n\n\n\n<li>2. Ist der Klick aus Punkt 1. erfolgt, so muss das <strong>PopUp-Fenster<\/strong> nur noch mit \u201e<strong>OK<\/strong>\u201c best\u00e4tigt werden. <\/li>\n\n\n\n<li>3. Des Weiteren darf man auch gerne einen Abstecher in die iOS Einstellungen-App machen, um nachzusehen ob alle Berechtigungen der Scriptable-App auf \u201e<strong>Erlaubt<\/strong>\u201c stehen. <\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1023\" height=\"958\" src=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3423-1.jpg\" alt=\"Die Berechtigungen einholen f\u00fcr die Scriptable-App!\" class=\"wp-image-6255\" srcset=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3423-1.jpg 1023w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3423-1-300x281.jpg 300w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3423-1-768x719.jpg 768w\" sizes=\"auto, (max-width: 1023px) 100vw, 1023px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\"><strong>Ein neues leeres Widget von Scriptable auf dem Home-Bildschirm platzieren!<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1. Geh zu deinem <strong>Home-Bildschirm<\/strong> und <strong>dr\u00fcckt lange<\/strong> auf eine beliebige Stelle, um den \u201e<strong>Wackelmodus<\/strong>\u201c (Wiggle Mode) aufzurufen. <\/li>\n\n\n\n<li>2. Dr\u00fccke dann das \u201e<strong>+<\/strong>\u201c <strong>Symbol<\/strong> oben links. <\/li>\n\n\n\n<li>3. Scrolle nach unten zu \u201e<strong>Scriptable<\/strong>\u201c \u2026<\/li>\n\n\n\n<li>4. \u2026 und w\u00e4hle die zweite (<strong>mittlere<\/strong>) <strong>Gr\u00f6\u00dfe<\/strong> aus. <\/li>\n\n\n\n<li>5. Klicke dann unten auf \u201e<strong>Widget hinzuf\u00fcgen<\/strong>\u201c. Nun habt Ihr ein neues leeres Widget auf dem Home-Bildschirm. <\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"635\" src=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3424-1-1024x635.jpg\" alt=\"Ein neues leeres Widget von Scriptable auf dem Home-Bildschirm platzieren!\" class=\"wp-image-6266\" srcset=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3424-1-1024x635.jpg 1024w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3424-1-300x186.jpg 300w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3424-1-768x477.jpg 768w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3424-1.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\"><strong>Damit alles richtig angezeigt wird, noch eine kleine Einstellung am leeren Widget!<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1. Bleibt bei eurem Home-Bildschirm und <strong>dr\u00fcckt lange<\/strong> auf das eben <strong>erstellte leere Widget<\/strong>, um den \u201e<strong>Wackelmodus<\/strong>\u201c aufzurufen<\/li>\n\n\n\n<li>2. Tippt im Wackelmodus auf das Widget, um das <strong>Kontextmen\u00fc<\/strong> aufzurufen, hier w\u00e4hlt Ihr den Schriftzug \u201e<strong>Widget bearbeiten<\/strong>\u201c. <\/li>\n\n\n\n<li>3. Als \u201e<strong>Skript<\/strong>\u201c w\u00e4hlt Ihr das oben erstellte JavaSkript (<strong>Next Bdays<\/strong>) aus der PopUp Liste aus. <\/li>\n\n\n\n<li>4. Als \u201e<strong>Parameter<\/strong>\u201c m\u00fcsst Ihr das oben im Einf\u00fchrungstext erw\u00e4hnte Schlagwort \u201e<strong>iCloud<\/strong>\u201c eingeben, um den Zugriff auf das Telefonbuch zu initiieren.<\/li>\n\n\n\n<li>5. Klicke irgendwo au\u00dferhalb des Kontextmen\u00fcs, um die Eingaben zu speichern. Nun findet im Hintergrund ein Datenabgleich statt und sp\u00e4testens 10 Sekunden sp\u00e4ter sollte das Widget vollst\u00e4ndig angezeigt werden. Fertig!<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1023\" height=\"962\" src=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3425.jpg\" alt=\"Damit alles richtig angezeigt wird, noch eine kleine Einstellung am leeren Widget!\" class=\"wp-image-6268\" srcset=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3425.jpg 1023w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3425-300x282.jpg 300w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2023\/02\/img_3425-768x722.jpg 768w\" sizes=\"auto, (max-width: 1023px) 100vw, 1023px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">\u2022 Der JavaScript-Code im <a href=\"https:\/\/anb030.de\/dl\/js_next_bdays_black.txt\">BVG Berlin<\/a> Stil mit den Farben Verkehrsgelb #F0CA00 und Dunkelgrau #202020.<\/p>\n\n\n<p><center><iframe loading=\"lazy\" src=\"https:\/\/anb030.de\/dl\/js_next_bdays_black.txt\" height=\"240\" width=\"640\"><\/iframe><\/center><\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">\u2022 Der JavaScript-Code im <a href=\"https:\/\/anb030.de\/dl\/js_next_bdays_yellow.txt\">S-Bahn Berlin<\/a> Stil mit den Farben Ockergelb #C0A754 und Rubinrot #861A22.<\/p>\n\n\n<p><center><iframe loading=\"lazy\" src=\"https:\/\/anb030.de\/dl\/js_next_bdays_yellow.txt\" height=\"240\" width=\"640\"><\/iframe><\/center><\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\"><strong><em>Hinweis:<\/em><\/strong> Dies ist ein von mir angepasster Scriptable Quellcode. Den Originalen Code findet Ihr bei <a rel=\"noreferrer noopener\" href=\"https:\/\/github.com\/lwitzani\/daysUntilBirthday\" target=\"_blank\">GitHub\/lwitzani<\/a><strong class=\"mr-2 flex-self-stretch\">!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Ich bin ein \u201eEin-Personen-Betrieb\u201c, arbeite hauptberuflich im Gesundheitswesen und betreibe diese Seite als Hobbyprojekt in meiner Freizeit. Wenn Ihnen meine Arbeit gef\u00e4llt (die Beitr\u00e4ge, die Hintergrundbilder, mein allgemeines Auftreten \u2026 einfach alles), so d\u00fcrfen Sie gerne in Erw\u00e4gung ziehen, \u00fcber die Kommentar-Funktion einen Kommentar zu hinterlassen oder mir eine kleine Spende per <a rel=\"noreferrer noopener\" href=\"https:\/\/www.paypal.com\/donate\/?hosted_button_id=TDP5X7EJD4SPQ\" target=\"_blank\">PayPal.com<\/a> zukommen zu lassen! Ihre Beteiligung ist unglaublich wertvoll und tr\u00e4gt viel zur Unterst\u00fctzung und Erhalt dieser werbefreien Seite bei!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manchmal ist mein K\u00f6rper auch nur Transportmittel meiner Gedanken und so hab ich mal wieder einen wichtigen Geburtstag verpasst. Nat\u00fcrlich bietet Apple seine Kalender Werksapplikation sowie Drittanbieter-Apps wie beispielsweise Fantastical diese Erinnerungsfunktion an, aber auch diese habe ich \u00fcbersehen. Das Problem ist hier, dass diese Erinnerungen per Push Mitteilungen auf dem Sperrbildschirm tags\u00fcber angezeigt werden [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[444,387],"tags":[392,416,435,437,388,390,389,396,436,408],"class_list":["post-6215","post","type-post","status-publish","format-standard","hentry","category-app-geheimtipp","category-iphone_ios","tag-app","tag-apple","tag-geheimtipp","tag-github","tag-ios","tag-ipad","tag-iphone","tag-online","tag-scriptable","tag-shortcuts","gallery-content-unit"],"_links":{"self":[{"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/posts\/6215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/comments?post=6215"}],"version-history":[{"count":0,"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/posts\/6215\/revisions"}],"wp:attachment":[{"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/media?parent=6215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/categories?post=6215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/tags?post=6215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}