{"id":917,"date":"2012-06-07T11:30:59","date_gmt":"2012-06-07T10:30:59","guid":{"rendered":"http:\/\/anb030.de\/a\/?p=917"},"modified":"2024-11-17T17:42:32","modified_gmt":"2024-11-17T16:42:32","slug":"ebook-uber-elektronische-musik-rauschen-als-rauschmittel","status":"publish","type":"post","link":"https:\/\/anb030.de\/a\/ebook-uber-elektronische-musik-rauschen-als-rauschmittel\/","title":{"rendered":"eBook \u00fcber elektronische Musik &#8222;Rauschen als Rauschmittel &#8211; 1992 bis 1997&#8220;"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-920\" title=\"Rauschen als Rauschmittel - Kostenloses eBook\" src=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2012\/06\/Rauschen-als-Rauschmittel.jpg\" alt=\"\" width=\"364\" height=\"211\" srcset=\"https:\/\/anb030.de\/a\/wp-content\/uploads\/2012\/06\/Rauschen-als-Rauschmittel.jpg 364w, https:\/\/anb030.de\/a\/wp-content\/uploads\/2012\/06\/Rauschen-als-Rauschmittel-300x173.jpg 300w\" sizes=\"auto, (max-width: 364px) 100vw, 364px\" \/><\/p>\n<p style=\"text-align: left;\">Heute habe ich f\u00fcr euch ein\u00a0<strong>Kostenloses<\/strong>\u00a0263\u00a0Seiten starkes eBook im Netz gefunden, genauer gesagt eine Diplomarbeit von Marco Reckmann aus dem Jahr 1998 &#8222;<strong>Rauschen als Rauschmittel<\/strong>&#8222;. Der junge Mann schreibt in seiner Arbeit \u00fcber elektronische Tanz Musik, sprich dem Nachtleben sowie die dazugeh\u00f6rigen Parties und ver\u00f6ffentlichte darin eine gro\u00dfe Sammlung an Flyer sowie Fotos von DJs, Live-Acts und dem feiernden Partyvolk. Die durchaus sch\u00f6nen Fotos und Flyer wurden alle in den Jahren 1992 bis 1997 geschossen, u.a. in diversen Clubs wie in Berlin, Leipzig, Jena, M\u00fcnchen u.s.w.! Nat\u00fcrlich wird euch in diesem PDF-eBook nicht nur Bildmaterial geboten, sondern auch Statements von K\u00fcnstlern aus Musikmagazinen dieser Zeit sowie Erkl\u00e4rungen und Anekdoten.<!--more--><\/p>\n<p style=\"text-align: left;\">Auf der Website <a title=\"Zur Photophunk.com Seite\" href=\"http:\/\/www.photophunk.com\/gadgets\/rauschen\/rauschen.html\" target=\"_blank\" rel=\"noopener\">Photophunk.com<\/a> gibt es noch viele weitere Information zu entdecken und den Download-Link zum eBook gibt\u00b4s hier: \u201c<a title=\"Zum eBook Download\" href=\"http:\/\/www.photophunk.com\/gadgets\/rauschen\/rauschen_als_rauschmittel.pdf\" target=\"_blank\" rel=\"noopener\">Rauschen als Rauschmittel<\/a>\u201d!<\/p>\n<p style=\"text-align: left;\">\u00a0 <script type=\"text\/javascript\"><!--\r\ngoogle_ad_client = \"ca-pub-9747266644223573\";\r\n\/* 468x15, Erstellt 25.11.09 *\/\r\ngoogle_ad_slot = \"5048860722\";\r\ngoogle_ad_width = 468;\r\ngoogle_ad_height = 15;\r\n\/\/-->\r\n<\/script>\r\n<script type=\"text\/javascript\"\r\nsrc=\"http:\/\/pagead2.googlesyndication.com\/pagead\/show_ads.js\">\r\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute habe ich f\u00fcr euch ein\u00a0Kostenloses\u00a0263\u00a0Seiten starkes eBook im Netz gefunden, genauer gesagt eine Diplomarbeit von Marco Reckmann aus dem Jahr 1998 &#8222;Rauschen als Rauschmittel&#8222;. Der junge Mann schreibt in seiner Arbeit \u00fcber elektronische Tanz Musik, sprich dem Nachtleben sowie die dazugeh\u00f6rigen Parties und ver\u00f6ffentlichte darin eine gro\u00dfe Sammlung an Flyer sowie Fotos von DJs, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57,98],"tags":[6,386],"class_list":["post-917","post","type-post","status-publish","format-standard","hentry","category-berlin-im-netz","category-webtipp","tag-berlin","tag-webtipp","gallery-content-unit"],"_links":{"self":[{"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/posts\/917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/comments?post=917"}],"version-history":[{"count":0,"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/posts\/917\/revisions"}],"wp:attachment":[{"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/media?parent=917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/categories?post=917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anb030.de\/a\/wp-json\/wp\/v2\/tags?post=917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}